{"id":9397,"date":"2015-12-10T10:55:13","date_gmt":"2015-12-10T09:55:13","guid":{"rendered":"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/angestellt-auf-zeit-diese-rechte-haben-leiharbeiter\/"},"modified":"2016-07-11T15:09:45","modified_gmt":"2016-07-11T14:09:45","slug":"angestellt-auf-zeit-diese-rechte-haben-leiharbeiter","status":"publish","type":"post","link":"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/angestellt-auf-zeit-diese-rechte-haben-leiharbeiter\/","title":{"rendered":"Ange\u00adstellt auf Zeit: Diese Rechte haben Leiharbeiter"},"content":{"rendered":"<p>Leiharbeiter werden von vielen Firmen gern eingesetzt, um zum Beispiel Engp\u00e4sse in der Produktion auszugleichen. Es ist aber oft unklar, welche <a title=\"Darum ADVOCARD\" href=\"https:\/\/www.advocard.de\/darum-advocard.html\" target=\"_blank\">Rechte<\/a> und Pflichten diese befristeteten Angestellten haben und was sie von den anderen Besch\u00e4ftigten im Entleihbetrieb unterscheidet.<\/p>\n<p><a title=\"Berufs-Rechtsschutz\" href=\"https:\/\/www.advocard.de\/berufs-rechtsschutz.html\" target=\"_blank\">Bei ungerechter Behandlung im Job hilft der Berufs-Rechtsschutz. &gt;&gt;<\/a><\/p>\n<h2>Welchen Lohn erhalten Leiharbeiter?<\/h2>\n<p>In der Regel schlie\u00dfen Leiharbeiter einen Tarifvertrag mit der Verleihfirma ab, in dem die Entlohnung geregelt ist. Es gilt ein <a href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/mindestlohn-berechnen-diese-bestandteile-fliessen-mit-ein\/\">Mindestlohn<\/a> von 8,20 Euro in Ostdeutschland und 8,80 Euro in Westdeutschland. Falls bei Ihrer Firma kein Tarifvertrag besteht, haben Sie als Leiharbeitnehmer Anspruch auf einen Lohn, der dem Ihrer Kollegen im Entleihunternehmen entspricht. Durch den geltenden Auskunftsanspruch d\u00fcrfen Sie den auch erfragen. Da der Arbeitsvertrag mit dem Verleihunternehmen geschlossen wird und dieses Ihr <a href=\"https:\/\/www.advocard.de\/arbeitgeber-rechtsschutz.html\" target=\"_blank\">Arbeitgeber<\/a> ist, m\u00fcssen Sie auch in den Zeitr\u00e4umen bezahlt werden, in denen Sie nicht f\u00fcr einen Entleihbetrieb arbeiten.<\/p>\n<h2><a href=\"https:\/\/www.advocard.de\/arbeitsrechtsschutz.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9263 size-full\" title=\"Darum ist ein Arbeitsrechtsschutz sinnvoll!\" src=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Arbeit_Karriere_A.png\" alt=\"Bei Arbeitsrechtsfragen sind wir Ihr Partner!\" width=\"313\" height=\"198\" srcset=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Arbeit_Karriere_A.png 313w, https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Arbeit_Karriere_A-300x190.png 300w\" sizes=\"(max-width: 313px) 100vw, 313px\"><\/a><\/h2>\n<h2>Rechte von Leih\u00adar\u00adbei\u00adtern: Gleiche Arbeitsbedingungen<\/h2>\n<p>Das Arbeitnehmer\u00fcberlassungsgesetz (A\u00dcG) regelt die <a title=\"Warum Rechtsschutz?\" href=\"https:\/\/www.advocard.de\/warum-rechtsschutz.html\" target=\"_blank\">Rechte<\/a> von Leiharbeitern in Deutschland. Wenn Sie im Rahmen von Leiharbeit in einer Firma t\u00e4tig sind, m\u00fcssen f\u00fcr Sie die gleichen Arbeitsbedingungen gelten wie f\u00fcr Ihre fest beim Entleihunternehmen angestellten Kollegen. Das bedeutet zum Beispiel auch, dass Sie Zugang zu Gemeinschaftseinrichtungen wie der Kantine erhalten m\u00fcssen und an Betriebsversammlungen teilnehmen d\u00fcrfen. Sie k\u00f6nnen auch nach Beendigung Ihrer T\u00e4tigkeit ein <a title=\"Qualifiziertes Arbeitszeugnis anfordern\" href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/qualifiziertes-arbeitszeugnis-anfordern-dies-sollten-sie-beachten\/\" target=\"_blank\">Arbeitszeugnis <\/a>einfordern. Dieses wird Ihnen allerdings von der Verleihfirma ausgestellt, die alle n\u00f6tigen Informationen beim Entleihunternehmen einholt.<\/p>\n<h2>Welcher Betriebs\u00adrat ist f\u00fcr die Leih\u00adar\u00adbei\u00adter zust\u00e4ndig?<\/h2>\n<p>Ab einer \u00dcberlassungszeit von drei Monaten d\u00fcrfen Leiharbeiter den <a title=\"Betriebsrat: Aufgaben und Pflichten\" href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/betriebsrat-aufgaben-und-pflichten-der-interessenvertretung\/\" target=\"_blank\">Betriebsrat<\/a> in der Entleihfirma mitw\u00e4hlen. Allerdings k\u00f6nnen Sie nicht selbst dort in den Betriebsrat gew\u00e4hlt werden, da Sie ja nicht bei dem Unternehmen angestellt sind. Stattdessen k\u00f6nnen Sie aber in Ihrem Verleihunternehmen Teil des Betriebsrats werden, sofern es dort einen gibt. Dieser ist auch in erster Linie f\u00fcr Sie zust\u00e4ndig. Wenn es allerdings um <a href=\"https:\/\/www.advocard.de\/arbeitsrechtsschutz.html#faq\" target=\"_blank\">Fragen<\/a> und Probleme rund um Ihre Arbeit im Entleihbetrieb geht, sollten Sie sich an den dortigen Betriebsrat wenden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leiharbeiter werden von vielen Firmen gern eingesetzt, um zum Beispiel Engp\u00e4sse in der Produktion auszugleichen. Es ist aber oft unklar, welche Rechte und Pflichten diese befristeteten Angestellten haben und was sie von den anderen Besch\u00e4ftigten im Entleihbetrieb unterscheidet. Bei ungerechter Behandlung im Job hilft der Berufs-Rechtsschutz. &gt;&gt; Welchen Lohn erhalten Leiharbeiter? In der Regel schlie\u00dfen [\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[3,13,63],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/9397"}],"collection":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/comments?post=9397"}],"version-history":[{"count":4,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/9397\/revisions"}],"predecessor-version":[{"id":9404,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/9397\/revisions\/9404"}],"wp:attachment":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/media?parent=9397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/categories?post=9397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/tags?post=9397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}