{"id":9027,"date":"2015-11-18T14:21:57","date_gmt":"2015-11-18T13:21:57","guid":{"rendered":"http:\/\/www.advocard.de\/streitlotse\/?p=9027"},"modified":"2015-12-22T17:31:04","modified_gmt":"2015-12-22T16:31:04","slug":"diese-10-arbeitszeugnis-formulierungen-sollten-sie-kennen","status":"publish","type":"post","link":"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/diese-10-arbeitszeugnis-formulierungen-sollten-sie-kennen\/","title":{"rendered":"Diese 10 Arbeits\u00adzeug\u00adnis-For\u00admu\u00adlie\u00adrun\u00adgen sollten Sie kennen"},"content":{"rendered":"<p>Das Arbeitszeugnis spiegelt Ihre Leistungen beim vorherigen Arbeitgeber wider und beurteilt Ihr Verhalten auf professioneller Ebene. Doch viele Formulierungen haben eine andere Bedeutung, als es im ersten Moment den Anschein macht. Dr. Gerwin Sonntag von der <a href=\"http:\/\/www.msbh.de\/\" target=\"_blank\">Kanzlei Bernzen Sonntag<\/a> kennt sich im Zeugnisdeutsch aus und wei\u00df, was mit bestimmten Floskeln gemeint ist. \u201eGrunds\u00e4tzlich haben Arbeitnehmer Anspruch auf ein ordentliches <a href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/qualifiziertes-arbeitszeugnis-anfordern-dies-sollten-sie-beachten\/\">Arbeitszeugnis<\/a>, in h\u00f6flicher und wohlwollender Sprache\u201c, sagt der Anwalt f\u00fcr Arbeitsrecht. \u201eDaher ist es auch nicht verwunderlich, dass Sie selten negative Beurteilungen finden.\u201c Wer aber trotzdem zwischen den Zeilen lesen will und die wahre Bedeutung der Worte kennen m\u00f6chte, der erlebt bei seiner n\u00e4chsten Bewerbung keine b\u00f6se \u00dcberraschung.<\/p>\n<p><a href=\"https:\/\/www.advocard.de\/berufs-rechtsschutz.html\" target=\"_blank\">Mit unserem Berufs-Rechtschutz erleben Sie im Job keine b\u00f6sen \u00dcberraschungen. &gt;&gt;<\/a><\/p>\n<h2>Die Top 10 der Arbeitszeugnis-Formulierungen<\/h2>\n<ol>\n<li>\u201e<strong>Sie verf\u00fcgt \u00fcber Fach\u00adwis\u00adsen und hat ein gesundes Selbstvertrauen.\u201c<br>\n<\/strong>Lesen Sie diese Floskel in Ihrem Arbeits\u00adzeug\u00adnis, \u00fcber\u00adspie\u00adlen Sie Ihr man\u00adgeln\u00addes Fach\u00adwis\u00adsen sehr&nbsp;gut.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li><strong>\u201eEr trug durch seine Gesel\u00adlig\u00adkeit zur Ver\u00adbes\u00adse\u00adrung des Betriebs\u00adkli\u00admas&nbsp;bei.\u201c<br>\n<\/strong>Sie glauben, Ihr Chef empfindet Sie als offen und auf\u00adge\u00adschlos\u00adsen? Falsch! Hiermit sagt er, dass Sie dem Alkohol nicht abgeneigt sind.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li><strong>\u201eSie war t\u00fcchtig und wusste sich gut zu verkaufen.\u201c<br>\n<\/strong>Die For\u00admu\u00adlie\u00adrung bedeutet, dass Sie ein sehr guter Selbst\u00addar\u00adstel\u00adler mit man\u00adgel\u00adhaf\u00adter Koope\u00adra\u00adti\u00adons\u00adbe\u00adreit\u00adschaft sind. Ihre Kollegen haben Sie als unan\u00adge\u00adneh\u00admen Mit\u00adar\u00adbei\u00adter wahr\u00adge\u00adnom\u00admen, der viel erz\u00e4hlt, wenn der Tag lang&nbsp;ist.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li><strong>\u201eEr bewies f\u00fcr die Belange der Beleg\u00adschaft stets Einf\u00fchlungsverm\u00f6gen.\u201c<br>\n<\/strong>Haben Sie diese Phrase entdeckt, dann sagt man Ihnen die Suche nach intimen Kontakten nach. Gesellt sich das Adjektiv \u201eumfassend\u201c dazu, unter\u00adstellt man Ihnen Homosexualit\u00e4t.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li><strong>\u201eSie erledigte alle ihr \u00fcber\u00adtra\u00adge\u00adnen Aufgaben pflicht\u00adbe\u00adwusst und ordnungsgem\u00e4\u00df.\u201c<br>\n<\/strong>Freuen Sie sich \u00fcber diese For\u00admu\u00adlie\u00adrung nicht zu fr\u00fch, denn hiermit sagt man Ihnen, dass Sie nur die Aufgaben <a href=\"https:\/\/www.advocard.de\/darum-advocard.html\" target=\"_blank\">zuver\u00adl\u00e4s\u00adsig erf\u00fcllt<\/a> haben, die man Ihnen auf\u00adge\u00adtra\u00adgen hat. Eigen\u00adin\u00aditia\u00adti\u00adve haben Sie jedoch nicht gezeigt.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li><strong>\u201eEr zeigte Ver\u00adst\u00e4nd\u00adnis f\u00fcr seine Arbeit.\u201c<br>\n<\/strong>Dieser Hinweis zielt auf Ihre schlechte Arbeit und mangelnde Leis\u00adtungs\u00adbe\u00adreit\u00adschaft ab.<\/li>\n<\/ol>\n<ol start=\"7\">\n<li><strong>\u201eIhr Verhalten gegen\u00fcber den Kollegen und Vor\u00adge\u00adsetz\u00adten war stets vorbildlich.\u201c<br>\n<\/strong>Wenn Ihr Chef erst nach den Kollegen erw\u00e4hnt wird, wird Ihre schlechte Beziehung zu ihm thematisiert.<\/li>\n<\/ol>\n<ol start=\"8\">\n<li><strong>\u201eEr hat alle Aufgaben zum eigenen und im Interesse der Firma gel\u00f6st.\u201c<br>\n<\/strong>Wenn Sie diese Arbeits\u00adzeug\u00adnis For\u00admu\u00adlie\u00adrung in Ihrer Beur\u00adtei\u00adlung lesen, dann sind Sie in ein b\u00f6ses Fett\u00adn\u00e4pf\u00adchen getreten und haben wahr\u00adschein\u00adlich Ihren Arbeit\u00adge\u00adber bestohlen.<\/li>\n<\/ol>\n<ol start=\"9\">\n<li><strong>\u201eWir best\u00e4\u00adti\u00adgen gerne, dass Sie mit Flei\u00df, Ehr\u00adlich\u00adkeit und P\u00fcnkt\u00adlich\u00adkeit an Ihre Aufgaben her\u00adan\u00adge\u00adgan\u00adgen&nbsp;ist.\u201c<br>\n<\/strong>Alle diese positiven Eigen\u00adschaf\u00adten ver\u00adtu\u00adschen, dass Ihnen leider die <a href=\"https:\/\/www.advocard.de\/rund-um-die-anwaltsuche.html\" target=\"_blank\">fachliche Qua\u00adli\u00adfi\u00adka\u00adti\u00adon<\/a> fehlte.<\/li>\n<\/ol>\n<ol start=\"10\">\n<li><strong>\u201eSeine umfang\u00adrei\u00adche Bildung machte ihn zu einem gesuchten Gespr\u00e4chspartner.\u201c<br>\n<\/strong>Anschei\u00adnend ist Ihrem Arbeit\u00adge\u00adber nicht entgangen, dass Sie sehr gespr\u00e4\u00adchig und w\u00e4hrend der Arbeits\u00adzeit immer f\u00fcr aus\u00adgie\u00adbi\u00adge private Unter\u00adhal\u00adtun\u00adgen zu haben&nbsp;waren.<a href=\"https:\/\/www.advocard.de\/arbeitsrechtsschutz.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9263 size-full\" title=\"\u00c4rger im Job? Bei Arbeitsrechtsfragen sind wir Ihr Partner!\" src=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Arbeit_Karriere_A.png\" alt=\"Bei Arbeitsrechtsfragen sind wir Ihr Partner!\" width=\"313\" height=\"198\" srcset=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Arbeit_Karriere_A.png 313w, https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Arbeit_Karriere_A-300x190.png 300w\" sizes=\"(max-width: 313px) 100vw, 313px\"><\/a><\/li>\n<\/ol>\n<h2>Schul\u00adno\u00adten im Arbeitszeugnis<\/h2>\n<p>Doch es gibt weitere Hinweise, die auf Ihre Arbeitsqualit\u00e4t hinweisen. Genau wie in den Schulzeugnissen von fr\u00fcher werden im <a href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/arbeitszeugnis-formulierungen-kein-anspruch-auf-bessere-beurteilung\/\">Arbeitszeugnis<\/a> Formulierungen genutzt, die den Noten von 1 bis 6 entsprechen.<\/p>\n<ul>\n<li>1 (sehr gut): ... hat Aufgaben stets zu unserer vollsten <a href=\"https:\/\/www.advocard.de\/advocard-im-test.html\" target=\"_blank\">Zufrie\u00adden\u00adheit<\/a> erledigt.<\/li>\n<li>2 (gut): ... hat Aufgaben stets zu unserer vollen Zufrie\u00adden\u00adheit erledigt.<\/li>\n<li>3 (befrie\u00addi\u00adgend): ... hat die Aufgaben zu unserer vollen Zufrie\u00adden\u00adheit erledigt.<\/li>\n<li>4 (aus\u00adrei\u00adchend): ... hat die Aufgaben zu unserer Zufrie\u00adden\u00adheit erledigt.<\/li>\n<li>5 (man\u00adgel\u00adhaft): ... hat die Aufgaben allgemein zu unserer Zufrie\u00adden\u00adheit erledigt.<\/li>\n<li>6 (unge\u00adn\u00fc\u00adgend): ... hat sich bem\u00fcht, die Aufgaben zu unserer Zufrie\u00adden\u00adheit zu erledigen.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.advocard.de\/arbeitsrechtsschutz.html\" target=\"_blank\">Im Job kommt es oft zu Streitereien. Darum ist ein Berufs-Rechtsschutz sinnvoll! &gt;&gt;<\/a><\/p>\n<p>Im Vergleich sind die Nuancen der unterschiedlichen Bewertungen leicht erkennbar. Dr. Gerwin Sonntag fasst zusammen: \u201eErhalten Sie ein \u201astets\u2019 und einen positiven Superlativ, dann k\u00f6nnen Sie sicher sein, dass Ihr <a href=\"https:\/\/www.advocard.de\/arbeitgeber-rechtsschutz.html\" target=\"_blank\">Arbeitgeber<\/a> mit Ihrer Leistung wirklich sehr zufrieden war und Sie als eifrigen Angestellten vermissen wird.\u201c Ein weiterer wichtiger Hinweis ist die Verwendung von Wortgruppen, die ihre Bedeutung aus der Kombination beziehen. Lobt man also Ihr Fachwissen und Ihr gesundes Selbstvertrauen, h\u00e4lt man Sie f\u00fcr inkompetent und gro\u00dfschn\u00e4uzig. Werden Kriterien \u00fcberbetont oder ironisch \u00fcbertrieben, wirft das ebenfalls kein gutes Licht auf Sie. \u201eGr\u00f6\u00dfte Genauigkeit\u201c besagt daher, dass Sie kleinlich und unflexibel sind.<\/p>\n<p>F\u00fchlen Sie sich in Ihrer Beurteilung ungerecht behandelt, weil bestimmte Behauptungen unwahr sind, k\u00f6nnen Sie auch juristisch dagegen vorgehen. Suchen Sie das pers\u00f6nliche Gespr\u00e4ch mit Ihrem Arbeitgeber und versuchen Sie die Angelegenheit ohne Anwalt zu kl\u00e4ren. Sind Sie dann immer noch unsicher, hilft Ihre <a href=\"https:\/\/www.advocard.de\/\" target=\"_blank\">Rechtschutzversicherung<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Arbeitszeugnis spiegelt Ihre Leistungen beim vorherigen Arbeitgeber wider und beurteilt Ihr Verhalten auf professioneller Ebene. Doch viele Formulierungen haben eine andere Bedeutung, als es im ersten Moment den Anschein macht. Dr. Gerwin Sonntag von der Kanzlei Bernzen Sonntag kennt sich im Zeugnisdeutsch aus und wei\u00df, was mit bestimmten Floskeln gemeint ist. \u201eGrunds\u00e4tzlich haben Arbeitnehmer [\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[3,14],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/9027"}],"collection":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/comments?post=9027"}],"version-history":[{"count":8,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/9027\/revisions"}],"predecessor-version":[{"id":9568,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/9027\/revisions\/9568"}],"wp:attachment":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/media?parent=9027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/categories?post=9027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/tags?post=9027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}