{"id":8675,"date":"2015-10-07T12:14:44","date_gmt":"2015-10-07T10:14:44","guid":{"rendered":"http:\/\/www.advocard.de\/streitlotse\/?p=8675"},"modified":"2016-07-05T16:56:49","modified_gmt":"2016-07-05T15:56:49","slug":"was-ist-eigentlich-ein-versaeumnisurteil","status":"publish","type":"post","link":"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/was-ist-eigentlich-ein-versaeumnisurteil\/","title":{"rendered":"Was ist eigent\u00adlich ein Vers\u00e4umnisurteil?"},"content":{"rendered":"<p>Wer zu sp\u00e4t kommt, den bestraft das Leben. Wer gar nicht kommt, den bestraft im Ernstfall das Gesetz \u2013 und zwar mit einem Vers\u00e4umnisurteil. Zumindest, wenn Sie vor <a href=\"https:\/\/www.advocard.de\/prozesskostenrechner.html\" target=\"_blank\">Gericht<\/a> trotz Vorladung nicht auftauchen.<\/p>\n<p><a href=\"https:\/\/www.advocard.de\/wohnungs-rechtsschutz.html\" target=\"_blank\">\u00c4rger mit dem Nachbarn? Gerichtstermin? Und Sie wissen gar nicht, wieso? Wir k\u00f6nnen helfen. &gt;&gt;<\/a><\/p>\n<p>Wir kennen es noch aus der <a href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/schulpflicht-passiert-wenn-das-kind-nicht-zur-schule-geht\/\">Schule<\/a>: Wer zu sp\u00e4t zum Unterricht kam, der stand mit Pech vor verschlossenen T\u00fcren. Das gab einen dicken Vermerk im Klassenbuch und man musste sich eine triftige Ausrede einfallen lassen. Damit hatte sich das Thema erledigt. Heute sieht das anders aus: Sind Sie vor Gericht geladen und nehmen den <a href=\"https:\/\/www.advocard.de\/rund-um-die-anwaltsuche.html\" target=\"_blank\">Termin<\/a> nicht wahr, kann der Kl\u00e4ger ein sogenanntes Vers\u00e4umnisurteil erwirken. Das ist allerdings eine Nummer saftiger als ein einfacher Eintrag ins Klassenbuch und Ihre Ausrede interessiert zu diesem Zeitpunkt niemanden mehr. Denn anstelle eines Klassenbucheintrages kommt es zu einem Urteil in dem Streitfall, ohne dass der Beklagte sich verteidigen kann.<\/p>\n<h2>Ver\u00ads\u00e4um\u00adnis\u00adur\u00adteil erhalten \u2013 es ist noch nicht alles verloren!<\/h2>\n<p>Wenn Ihnen ein Vers\u00e4umnisurteil ins Haus flattert und Sie v\u00f6llig \u00fcberrascht sind, dann ist schon Einiges schief gelaufen. Es ist aber v\u00f6llig egal, ob Sie irgendwann f\u00fcr sich beschlossen haben, die <a href=\"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/post-streik-was-verbraucher-nun-wissen-sollten\/\" target=\"_blank\">Post<\/a> grunds\u00e4tzlich nicht mehr zu \u00f6ffnen oder das Schreiben einfach verloren haben. Sie wurden verklagt und zu diesem Zeitpunkt nicht nur das: Sie haben es auch vers\u00e4umt, sich zu dem Fall zu \u00e4u\u00dfern oder zur Verhandlung zu erscheinen. Nun kann das Urteil in der Streitsache auf Ihre Kosten gehen, ohne dass Sie <a href=\"https:\/\/www.advocard.de\/warum-rechtsschutz.html\" target=\"_blank\">sich rechtfertigen<\/a> konnten. Anders als in der Schule gilt in so einem Fall f\u00fcr Sie: Besser sp\u00e4te als nie. \u201eSie m\u00fcssen das Vers\u00e4umnisurteil nicht sang und klanglos akzeptieren. Wenn Sie innerhalb einer zweiw\u00f6chigen Frist Einspruch gegen das Urteil einlegen, k\u00f6nnen Sie Ihre Einwendungen und Beweise noch vortragen und eine Aufhebung des Vers\u00e4umnisurteils erreichen\u201c, erkl\u00e4rt Anwalt Ulrich Kelch, zust\u00e4ndig f\u00fcr allgemeines Zivilrecht bei der <a href=\"http:\/\/www.linten.de\/home.html\" target=\"_blank\">Kanzlei Linten Rechtsanw\u00e4lte<\/a>.<\/p>\n<h2>Einspruch gegen ein Vers\u00e4umnisurteil<\/h2>\n<p>Aber ruhen Sie sich nicht zu lang auf der faulen Haut aus! Verpassen Sie diese Frist von zwei Wochen, wird das Urteil rechtskr\u00e4ftig und Sie k\u00f6nnen dagegen nicht mehr vorgehen. Schlie\u00dfen Sie sich in jedem Fall mit einem Anwalt oder Ihrer <a href=\"https:\/\/www.advocard.de\/darum-advocard.html\" target=\"_blank\">Rechtsschutzversicherung<\/a> kurz, wenn Sie Einspruch gegen ein Vers\u00e4umnisurteil einlegen wollen. Denn von Fall zu Fall kann es auch sinnvoller sein, das Urteil zu akzeptieren. Ein erfahrener Anwalt wird Sie nicht nur hinsichtlich Ihrer Erfolgsaussichten beraten, sondern auch hinsichtlich der <a href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/anwaltskosten-was-kostet-rechtlicher-rat-eigentlich\/\">Kosten<\/a>.<\/p>\n<p><a href=\"https:\/\/www.advocard.de\/privat-rechtsschutz.html\" target=\"_blank\">Ein Rechtsstreit bereitet Ihnen Kopfzerbrechen? Hier bekommen Sie Unterst\u00fctzung! &gt;&gt;<\/a><\/p>\n<p>\u201eIst Ihr Einspruch zul\u00e4ssig, wird Ihr Rechtsstreit wieder in den Stand zur\u00fcckversetzt, in dem er vor Erlass des Vers\u00e4umnisurteils war. Zum zweiten Gerichtstermin sollten Sie als Beklagter auf jeden Fall erscheinen. Wird auch der zweite Termin vers\u00e4umt, ergeht ein zweites Vers\u00e4umnisurteil\u201c, sagt Ulrich Kelch. Das hebt zwar das erste Urteil auf. Aber hiergegen kann kein Einspruch mehr eingelegt werden \u2013 auch nicht mit Entschuldigung der Eltern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer zu sp\u00e4t kommt, den bestraft das Leben. Wer gar nicht kommt, den bestraft im Ernstfall das Gesetz \u2013 und zwar mit einem Vers\u00e4umnisurteil. Zumindest, wenn Sie vor Gericht trotz Vorladung nicht auftauchen. \u00c4rger mit dem Nachbarn? Gerichtstermin? Und Sie wissen gar nicht, wieso? Wir k\u00f6nnen helfen. &gt;&gt; Wir kennen es noch aus der Schule: [\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[7,28],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/8675"}],"collection":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/comments?post=8675"}],"version-history":[{"count":3,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/8675\/revisions"}],"predecessor-version":[{"id":8680,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/8675\/revisions\/8680"}],"wp:attachment":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/media?parent=8675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/categories?post=8675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/tags?post=8675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}