{"id":4701,"date":"2014-12-01T11:16:01","date_gmt":"2014-12-01T11:16:01","guid":{"rendered":"http:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/persoenliche-daten-im-internet-microsoft-und-yahoo-setzen-eugh-urteil-um\/"},"modified":"2015-07-30T10:50:25","modified_gmt":"2015-07-30T08:50:25","slug":"persoenliche-daten-im-internet-microsoft-und-yahoo-setzen-eugh-urteil-um","status":"publish","type":"post","link":"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/persoenliche-daten-im-internet-microsoft-und-yahoo-setzen-eugh-urteil-um\/","title":{"rendered":"Per\u00ads\u00f6n\u00adli\u00adche Daten im Internet: Microsoft und Yahoo setzen EuGH-Urteil um"},"content":{"rendered":"<p>Im Mai 2014 st\u00e4rkte der Europ\u00e4ische Gerichtshof das Recht auf Vergessenwerden: Suchmaschinen m\u00fcssen pers\u00f6nliche Daten im Internet auf Antrag von Usern l\u00f6schen. Google startete umgehend damit, das <a title=\"Gerichtsurteile\" href=\"https:\/\/www.advocard.de\/streitlotse\/?s=urteil\">Urteil<\/a> bez\u00fcglich ungewollter personenbezogener Suchergebnisse umzusetzen \u2013 nun ziehen Microsoft und Yahoo nach. Vertreter beider Firmen haben gegen\u00fcber dem \"Wall Street Journal\" best\u00e4tigt, dass sie begonnen haben, bestimmte Links aus ihren Ergebnislisten zu entfernen. Wie viele L\u00f6schantr\u00e4ge vorliegen, dar\u00fcber machten weder Microsoft noch Yahoo genaue Angaben.<\/p>\n<p><a title=\"Online einen Anwalt suchen.\" href=\"https:\/\/www.advocard.de\/rund-um-die-anwaltsuche.html\" target=\"_blank\">Verk\u00fcrzen Sie Ihre Suche. Mit uns finden Sie schnell einen kompetenten Anwalt. &gt;&gt; <\/a><\/p>\n<p>Urspr\u00fcnglich richtete sich die Klage gegen Google. Der Europ\u00e4ische Gerichtshof entschied in einem <a href=\"https:\/\/www.advocard.de\/\">Streit<\/a> zwischen Spanien, der spanischen Datenschutzbeh\u00f6rde Agencia Espa\u00f1ola de Protecci\u00f3n de Datos&nbsp;und dem amerikanischen Suchmaschinen-Konzern. Das Urteil (AZ C121\/12), das auf Grundlage der Richtlinie zum <a href=\"https:\/\/www.advocard.de\/streitlotse\/kategorie\/internet-und-konsum\/datenschutz\/\">Datenschutz<\/a> in der EU gef\u00e4llt wurde, verpflichtet Betreiber von Suchmaschinen auf Antrag einer Person, Links aus der Ergebnisliste zu l\u00f6schen, die bei&nbsp;einer Suche nach ihrem Namen erscheinen. Seit Juni k\u00fcmmert sich Google um L\u00f6schantr\u00e4ge von Usern, die ihre pers\u00f6nlichen Daten im Internet sch\u00fctzen wollen.<\/p>\n<p>Sprecher von Microsoft und Yahoo k\u00fcndigten an, jede Anfrage zur Umsetzung des vom EuGH gest\u00e4rkten Rechts auf Vergessenwerden gr\u00fcndlich zu pr\u00fcfen. Dabei solle die Balance zwischen dem Recht auf Privatsph\u00e4re und dem Recht der \u00d6ffentlichkeit auf Informationen und freie Meinungs\u00e4u\u00dferung abgewogen werden. Vor allem bei Personen des \u00f6ffentlichen Lebens sei dies besonders wichtig, betonte der EuGH in seiner Urteilsschrift.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Mai 2014 st\u00e4rkte der Europ\u00e4ische Gerichtshof das Recht auf Vergessenwerden: Suchmaschinen m\u00fcssen pers\u00f6nliche Daten im Internet auf Antrag von Usern l\u00f6schen. Google startete umgehend damit, das Urteil bez\u00fcglich ungewollter personenbezogener Suchergebnisse umzusetzen \u2013 nun ziehen Microsoft und Yahoo nach. Vertreter beider Firmen haben gegen\u00fcber dem \"Wall Street Journal\" best\u00e4tigt, dass sie begonnen haben, bestimmte [\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[29,7],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/4701"}],"collection":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/comments?post=4701"}],"version-history":[{"count":3,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/4701\/revisions"}],"predecessor-version":[{"id":6567,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/4701\/revisions\/6567"}],"wp:attachment":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/media?parent=4701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/categories?post=4701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/tags?post=4701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}