{"id":19910,"date":"2019-10-02T08:46:01","date_gmt":"2019-10-02T07:46:01","guid":{"rendered":"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/verbraucherrecht\/der-rechtsweg-ist-ausgeschlossen-stimmt-das-wirklich\/"},"modified":"2019-10-14T13:55:23","modified_gmt":"2019-10-14T12:55:23","slug":"der-rechtsweg-ist-ausgeschlossen-stimmt-das-wirklich","status":"publish","type":"post","link":"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/verbraucherrecht\/der-rechtsweg-ist-ausgeschlossen-stimmt-das-wirklich\/","title":{"rendered":"\"Der Rechtsweg ist aus\u00adge\u00adschlos\u00adsen\": Stimmt das wirklich?"},"content":{"rendered":"<p>Bei Gewinnspielen liest man h\u00e4ufig die Klausel: \"Der Rechtsweg ist ausgeschlossen.\"&nbsp;Hier liest du, was das bedeutet und ob dieser Satz&nbsp;in jedem Fall als rechtliche Absicherung des Gewinnspiel-Veranstalters gen\u00fcgt.<\/p>\n<p><a title=\"Privat-Rechtschutz von ADVOCARD\" href=\"https:\/\/www.advocard.de\/privatrechtsschutz\/\" target=\"_blank\" rel=\"noopener\">Welche rechtlichen Anspr\u00fcche habe ich eigentlich? Bei uns ist die Beratung im&nbsp;konkreten Fall mit drin. &gt;&gt;<\/a><\/p>\n<h2>Der Rechtsweg bei Gewinn\u00adspie\u00adlen: Kann man Gewinne einklagen?<\/h2>\n<p>Grunds\u00e4tzlich hat in Deutschland jeder die M\u00f6glichkeit, den <strong>Rechtsweg<\/strong> zu beschreiten und dadurch strittige Sachverhalte von einem Gericht \u00fcberpr\u00fcfen zu lassen.&nbsp;<strong>Nicht einklagen<\/strong> kann man gem\u00e4\u00df \u00a7 762 B\u00fcrgerliches Gesetzbuch (BGB) allerdings Gewinne aus (illegalen) <strong>Spielen und Wetten<\/strong> sowie Spiel- und Wettschulden.<\/p>\n<p>Veranstalter von<strong> staatlich genehmigten Lotterien und Gewinnspielen<\/strong> nutzen ebenfalls gern den Hinweis \"Der Rechtsweg ist ausgeschlossen\" \u2013 zum Beispiel, um sich vor Klagen von Teilnehmern zu sch\u00fctzen, die bei einem korrekt durchgef\u00fchrten Gewinnspiel nicht gewonnen haben und nun auf gut Gl\u00fcck versuchen, vor Gericht einen Gewinn zu erstreiten.<\/p>\n<p>&nbsp;<\/p>\n<h2>Rechtsweg-Klausel kann in den AGB wirksam sein<\/h2>\n<p>Grunds\u00e4tzlich bedeutet dieser einseitige \"Ausschluss\" des Rechtswegs lediglich, dass der <strong>Gewinnspiel-Veranstalter&nbsp;den Rechtsweg ablehnt<\/strong> \u2013 und nicht zwingend, dass Teilnehmer&nbsp;keine M\u00f6glichkeit haben, vor Gericht zu ziehen.<\/p>\n<p><strong>Allerdings kann die Klausel \"Der Rechtsweg ist ausgeschlossen\" bei einem Gewinnspiel tats\u00e4chlich rechtlich wirksam sein <\/strong>\u2013 zum Beispiel, wenn der Satz in den Allgemeinen Gesch\u00e4ftsbedingungen (<strong>AGB<\/strong>) steht. Das entschied das <strong>Landgericht Hannover<\/strong> 2009 (AZ 1 O 77\/08) im Fall einer Klage von zwei Radioh\u00f6rern, die ihren vermeintlichen Anspruch auf einen&nbsp;Preis aus einem Rundfunk-Gewinnspiel vor Gericht durchsetzen wollten.<\/p>\n<p>Im verhandelten Fall konnten H\u00f6rer eines Radiosenders ein <strong>Preisgeld<\/strong> gewinnen, wenn sie einen 10-Euro-Schein mit einer bestimmten Seriennummer besa\u00dfen. Auf seiner Internetseite&nbsp;hatte der Sender die <strong>Teilnahmebedingungen mit dem Zusatz \"Der Rechtsweg ist ausgeschlossen\" ver\u00f6ffentlicht<\/strong>. Teilnehmer konnten sich die Bedingungen auch ausdrucken.<\/p>\n<p>Das Gericht wertete dieses Vorgehen des Senders als ausreichend transparent. Zudem h\u00e4tten die H\u00f6rer durch ihre Teilnahme <strong>keine Nachteile<\/strong> f\u00fcrchten m\u00fcssen, sondern konnten nur gewinnen. Der Radiosender habe ein <strong>berechtigtes Interesse<\/strong> daran, Rechtsstreitigkeiten mit einer potenziell sehr gro\u00dfen Zahl an H\u00f6rern zu vermeiden \u2013 dieses Interesse wiege schwerer als das Gewinninteresse einzelner Personen, so das Gericht.<\/p>\n<p>&nbsp;<\/p>\n<h2>Gewinn\u00adzu\u00adsa\u00adge: Bei T\u00e4uschung steht der Rechtsweg offen<a href=\"http:\/\/advocard.de\/info\/privat\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-18457 size-full\" title=\"Privatrechtsschutz von ADVOCARD\" src=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2019\/02\/Vererben_Vorsorgen_A-300x190.png\" alt=\"Mehr Informationen zum Thema Rechtsschutz\" width=\"300\" height=\"190\"><\/a><\/h2>\n<p>Anders sieht es aus, wenn ein <strong>Gewinn ausdr\u00fccklich versprochen, aber nicht ausgeh\u00e4ndigt<\/strong> wurde. <a title=\"Warum Rechtsschutz?\" href=\"https:\/\/www.advocard.de\/rechtsschutzversicherung\/\" target=\"_blank\" rel=\"noopener\">Das&nbsp;m\u00fcssen Teilnehmer nicht akzeptieren<\/a>&nbsp;\u2013 so ist es in&nbsp;\u00a7 661a B\u00fcrgerliches Gesetzbuch (BGB) unter dem Stichwort \"<strong>Gewinnzusagen<\/strong>\" geregelt.<\/p>\n<p>Unseri\u00f6se Unternehmen&nbsp;versenden h\u00e4ufig&nbsp;<strong>Anschreiben, wonach der Adressat&nbsp;Geld gewonnen habe <\/strong>\u2013 oft sogar ohne, dass dieser sich an eine Teilnahme an einem Gewinnspiel \u00fcberhaupt erinnern kann. Tats\u00e4chlich jedoch wird der angebliche Gewinn nicht ausgeh\u00e4ndigt, sondern dient nur dazu, den Adressaten beispielsweise zur Teilnahme an einer <strong>Verkaufsveranstaltung<\/strong> (\"<a title=\"Kaffeefahrt: Gewinnzusage und Widerruf \u2013 Ihre Rechte\" href=\"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/kaffeefahrten-gewinnzusage-und-widerruf-ihre-rechte\/\" target=\"_blank\" rel=\"noopener\">Kaffeefahrt<\/a>\") oder zu einer <strong>Warenbestellung<\/strong> zu bewegen.<\/p>\n<p>In einem solchen Fall entschied das <strong>Oberlandesgericht K\u00f6ln<\/strong> 2010, dass ein <strong>Versandunternehmen den zugesagten Geldgewinn auch auszahlen m\u00fcsse<\/strong> (AZ 21 U 2\/10). Die Gewinnzusage&nbsp;wurde im verhandelten Fall lediglich im Kleingedruckten&nbsp;und&nbsp;sehr&nbsp;undurchsichtig relativiert. Der Adressat m\u00fcsse so den <strong>Eindruck erhalten, dass er gewonnen habe<\/strong>, so die Einsch\u00e4tzung des Gerichts&nbsp;\u2013 und nicht etwa, dass er durch eine Warenbestellung nur eine Chance auf den Gewinn habe.<\/p>\n<p>Wird auf diese Weise also <strong>bewusst get\u00e4uscht<\/strong>, steht dir als Teilnehmer immer der Rechtsweg offen. Auch ein Hinweis, wonach&nbsp;dieser angeblich ausgeschlossen sei, \u00e4ndert daran nichts. Die Beratung durch einen<strong> Anwalt, <\/strong>der den individuellen Fall pr\u00fcft, ist jedoch zu empfehlen.<\/p>\n<div class=\"fazitbox\">\n<div class=\"fazitbox-titel\">FAZIT<\/div>\n<ul>\n<li>Der Hinweis \"Der Rechtsweg ist aus\u00adge\u00adschlos\u00adsen\"&nbsp;soll Gewinn\u00adspiel\u00adteil\u00adneh\u00admer&nbsp;h\u00e4ufig davon abhalten, auf gut Gl\u00fcck Gewinne einzuklagen.<\/li>\n<li>Die Klausel&nbsp;kann aber tat\u00ads\u00e4ch\u00adlich rechts\u00adwirk\u00adsam sein, wenn das Interesse des Ver\u00adan\u00adstal\u00adters, Rechts\u00adstrei\u00adtig\u00adkei\u00adten zu vermeiden, schwerer wiegt als das Interesse des Teil\u00adneh\u00admers am Gewinn.<\/li>\n<li>Konkrete Gewinn\u00adzu\u00adsa\u00adgen sind jedoch rechtlich ver\u00adbind\u00adlich&nbsp;und k\u00f6nnen notfalls ein\u00adge\u00adklagt werden \u2013 \"Rechtsweg ausgeschlossen\"-Klauseln sind&nbsp;hier unwirksam.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bei Gewinnspielen liest man h\u00e4ufig die Klausel: \"Der Rechtsweg ist ausgeschlossen.\"&nbsp;Hier liest du, was das bedeutet und ob dieser Satz&nbsp;in jedem Fall als rechtliche Absicherung des Gewinnspiel-Veranstalters gen\u00fcgt. Welche rechtlichen Anspr\u00fcche habe ich eigentlich? Bei uns ist die Beratung im&nbsp;konkreten Fall mit drin. &gt;&gt; Der Rechtsweg bei Gewinn\u00adspie\u00adlen: Kann man Gewinne einklagen? Grunds\u00e4tzlich hat in [\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[28],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/19910"}],"collection":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/comments?post=19910"}],"version-history":[{"count":4,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/19910\/revisions"}],"predecessor-version":[{"id":19954,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/19910\/revisions\/19954"}],"wp:attachment":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/media?parent=19910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/categories?post=19910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/tags?post=19910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}