{"id":12741,"date":"2016-12-15T15:14:02","date_gmt":"2016-12-15T14:14:02","guid":{"rendered":"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/facebook-betriebsrat-darf-beim-firmenprofil-mitreden\/"},"modified":"2016-12-15T16:32:26","modified_gmt":"2016-12-15T15:32:26","slug":"facebook-betriebsrat-darf-beim-firmenprofil-mitreden","status":"publish","type":"post","link":"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/facebook-betriebsrat-darf-beim-firmenprofil-mitreden\/","title":{"rendered":"Facebook: Betriebs\u00adrat darf beim Fir\u00admen\u00adpro\u00adfil mitreden"},"content":{"rendered":"<p>Unternehmen m\u00fcssen ihren Betriebsrat konsultieren, wenn sie ihr <a title=\"Arbeitgeber-Rechtsschutz\" href=\"https:\/\/www.advocard.de\/arbeitgeber-rechtsschutz\/\" target=\"_blank\">Firmenprofil<\/a> auf Facebook mit einer Kommentarfunktion ausstatten. Andernfalls muss diese gel\u00f6scht werden. Das hat jetzt das&nbsp;Bundesarbeitsgericht entschieden.<\/p>\n<p><a title=\"Der 360\u00b0-Rechtsschutz von ADVOCARD\" href=\"https:\/\/www.advocard.de\/360-grad\/\" target=\"_blank\">Sicher ist sicher \u2013 gut beraten mit unserem Rechtsschutz. &gt;&gt;<\/a><\/p>\n<p>Das Urteil geht auf die Klage des Konzernbetriebsrats eines nordrhein-westf\u00e4lischen Blutspendedienstes zur\u00fcck. Das Unternehmen hatte ein Facebook-Firmenprofil ins Netz gestellt. Dazu geh\u00f6rte auch eine Kommentarfunktion, \u00fcber die die Nutzer ihre Meinung \u00fcber den Betrieb \u00e4u\u00dferten. Darunter war&nbsp;unter anderem auch negative Kritik, die sich zwei <a title=\"Berufs-Rechtsschutz von ADVOCARD\" href=\"https:\/\/www.advocard.de\/berufsrechtsschutz\/\" target=\"_blank\">einzelnen Mitarbeitern<\/a> zuordnen lie\u00df.<\/p>\n<p>Diese eindeutige Identifizierung stie\u00df dem Betriebsrat unangenehm auf, und er forderte die <a title=\"Gewerberechtsschutz\" href=\"https:\/\/www.advocard.de\/info\/gewerbe\/\" target=\"_blank\">Unternehmensf\u00fchrung<\/a> auf, die Beitr\u00e4ge zu l\u00f6schen. Als dies nicht geschah, ging der Streitfall durch alle Instanzen bis zum Bundesarbeitsgericht.<\/p>\n<p><a href=\"https:\/\/www.advocard.de\/advocard-im-test\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9267 size-full\" title=\"Verlassen Sie sich im Streitfall auf den Testsieger!\" src=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Vererben_Vorsorgen_A.png\" alt=\"Rechtsschutz\" width=\"313\" height=\"198\" srcset=\"https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Vererben_Vorsorgen_A.png 313w, https:\/\/www.advocard.de\/streitlotse\/wp-content\/uploads\/2015\/12\/Vererben_Vorsorgen_A-300x190.png 300w\" sizes=\"(max-width: 313px) 100vw, 313px\"><\/a>Ein Firmenprofil auf Facebook ist inhaltlich eher eine Sache der PR- und Marketingabteilung. Der <a title=\"Betriebsrat: Aufgaben und Pflichten\" href=\"https:\/\/www.advocard.de\/streitlotse\/arbeit-und-karriere\/betriebsrat-aufgaben-und-pflichten-der-interessenvertretung\/\" target=\"_blank\">Betriebsrat<\/a> hat damit eigentlich nichts zu tun. Dennoch gaben ihm die Richter in Erfurt zumindest teilweise recht (AZ 1 ABR 7\/15). Wie dieser sahen sie die Kommentarfunktion und damit die Meinung von Nutzern zu einzelnen Mitarbeitern als eine Form der&nbsp;technischen Verhaltens- und Leistungskontrolle an. F\u00fcr eine solche ist tats\u00e4chlich die Arbeitnehmervertretung zust\u00e4ndig und muss im Unternehmen dazu ihre Einwilligung geben.<\/p>\n<p>Der Blutspendedienst muss daher die Kommentarfunktion bei <a title=\"WhatsApp-Daten: Weitergabe an Facebook rechtens?\" href=\"https:\/\/www.advocard.de\/streitlotse\/internet-und-konsum\/whatsapp-datenschutz-weitergabe-an-facebook-rechtens\/\" target=\"_blank\">Facebook<\/a> abschalten. Er darf sie erst wieder einf\u00fchren, wenn er dar\u00fcber eine einvernehmliche Regelung mit dem Betriebsrat gefunden hat. Alle weiteren Bestandteile des Firmenprofils sind davon nicht betroffen.<\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer;\">Merken<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unternehmen m\u00fcssen ihren Betriebsrat konsultieren, wenn sie ihr Firmenprofil auf Facebook mit einer Kommentarfunktion ausstatten. Andernfalls muss diese gel\u00f6scht werden. Das hat jetzt das&nbsp;Bundesarbeitsgericht entschieden. Sicher ist sicher \u2013 gut beraten mit unserem Rechtsschutz. &gt;&gt; Das Urteil geht auf die Klage des Konzernbetriebsrats eines nordrhein-westf\u00e4lischen Blutspendedienstes zur\u00fcck. Das Unternehmen hatte ein Facebook-Firmenprofil ins Netz gestellt. [\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[3,13,7,76],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/12741"}],"collection":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/comments?post=12741"}],"version-history":[{"count":3,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/12741\/revisions"}],"predecessor-version":[{"id":12746,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/posts\/12741\/revisions\/12746"}],"wp:attachment":[{"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/media?parent=12741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/categories?post=12741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.advocard.de\/streitlotse\/wp-json\/wp\/v2\/tags?post=12741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}